{"id":9740,"date":"2021-09-13T18:07:32","date_gmt":"2021-09-13T22:07:32","guid":{"rendered":"https:\/\/www.jirauenergia.com.br\/?post_type=programas&#038;p=9740"},"modified":"2021-10-21T11:25:36","modified_gmt":"2021-10-21T14:25:36","slug":"programa-de-conservacao-da-flora","status":"publish","type":"programas","link":"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-conservacao-da-flora","title":{"rendered":"Programa de Conserva\u00e7\u00e3o da Flora"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Objetivo<\/strong><br>Este Programa visa minimizar os impactos na vegeta\u00e7\u00e3o atrav\u00e9s do monitoramento, resgate e conserva\u00e7\u00e3o do germoplasma vegetal. Inclui a medi\u00e7\u00e3o de tipos arb\u00f3reos, a determina\u00e7\u00e3o de par\u00e2metros de diversidade do ecossistema e o envolvimento da comunidade na conserva\u00e7\u00e3o da flora. Este programa engloba 03 (tr\u00eas) subprogramas: (i) Subprograma de Monitoramento da Flora; (ii) Subprograma de Resgate e Conserva\u00e7\u00e3o de Germoplasma Vegetal; (iii) Subprograma de Revegeta\u00e7\u00e3o da \u00c1rea de Preserva\u00e7\u00e3o Permanente (APP) do Futuro Reservat\u00f3rio.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Resumo<\/strong><br>A UHE Jirau est\u00e1 situada nos dom\u00ednios da floresta Amaz\u00f4nica, em um trecho do rio Madeira. A Amaz\u00f4nia \u00e9 a maior \u00e1rea de floresta cont\u00ednua do planeta e apresenta consider\u00e1vel diversidade clim\u00e1tica, ecol\u00f3gica, entre outras. Historicamente a vegeta\u00e7\u00e3o nativa local vem sendo modificada pela extra\u00e7\u00e3o ilegal de madeira e a abertura de \u00e1reas para agricultura e pecu\u00e1ria.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Fase Atual<\/strong><br>Em desenvolvimento<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Executor<\/strong><br>CENARGEN\/Embrapa e Cooperativa dos Produtores Rurais do Observat\u00f3rio Ambiental Jirau (COOPPROJIRAU)<\/li><\/ul>","protected":false},"featured_media":13232,"template":"","categoria_de_programas":[52],"class_list":["post-9740","programas","type-programas","status-publish","has-post-thumbnail","hentry","categoria_de_programas-programas-ambientais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Programa de Conserva\u00e7\u00e3o da Flora - Jirau Energia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-conservacao-da-flora\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programa de Conserva\u00e7\u00e3o da Flora - Jirau Energia\" \/>\n<meta property=\"og:description\" content=\"ObjetivoEste Programa visa minimizar os impactos na vegeta\u00e7\u00e3o atrav\u00e9s do monitoramento, resgate e conserva\u00e7\u00e3o do germoplasma vegetal. Inclui a medi\u00e7\u00e3o de tipos arb\u00f3reos, a determina\u00e7\u00e3o de par\u00e2metros de diversidade do ecossistema e o envolvimento da comunidade na conserva\u00e7\u00e3o da flora. Este programa engloba 03 (tr\u00eas) subprogramas: (i) Subprograma de Monitoramento da Flora; (ii) Subprograma de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-conservacao-da-flora\" \/>\n<meta property=\"og:site_name\" content=\"Jirau Energia\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-21T14:25:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2020-10-23-at-08.20.20.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora\",\"url\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora\",\"name\":\"Programa de Conserva\u00e7\u00e3o da Flora - Jirau Energia\",\"isPartOf\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2020-10-23-at-08.20.20.jpeg\",\"datePublished\":\"2021-09-13T22:07:32+00:00\",\"dateModified\":\"2021-10-21T14:25:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#primaryimage\",\"url\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2020-10-23-at-08.20.20.jpeg\",\"contentUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2020-10-23-at-08.20.20.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.jirauenergia.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programa de Conserva\u00e7\u00e3o da Flora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#website\",\"url\":\"https:\/\/www.jirauenergia.com.br\/\",\"name\":\"Jirau Energia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jirauenergia.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#organization\",\"name\":\"Jirau Energia\",\"url\":\"https:\/\/www.jirauenergia.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png\",\"contentUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png\",\"width\":300,\"height\":86,\"caption\":\"Jirau Energia\"},\"image\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programa de Conserva\u00e7\u00e3o da Flora - Jirau Energia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-conservacao-da-flora","og_locale":"en_US","og_type":"article","og_title":"Programa de Conserva\u00e7\u00e3o da Flora - Jirau Energia","og_description":"ObjetivoEste Programa visa minimizar os impactos na vegeta\u00e7\u00e3o atrav\u00e9s do monitoramento, resgate e conserva\u00e7\u00e3o do germoplasma vegetal. Inclui a medi\u00e7\u00e3o de tipos arb\u00f3reos, a determina\u00e7\u00e3o de par\u00e2metros de diversidade do ecossistema e o envolvimento da comunidade na conserva\u00e7\u00e3o da flora. Este programa engloba 03 (tr\u00eas) subprogramas: (i) Subprograma de Monitoramento da Flora; (ii) Subprograma de [&hellip;]","og_url":"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-conservacao-da-flora","og_site_name":"Jirau Energia","article_modified_time":"2021-10-21T14:25:36+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2020-10-23-at-08.20.20.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora","url":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora","name":"Programa de Conserva\u00e7\u00e3o da Flora - Jirau Energia","isPartOf":{"@id":"https:\/\/www.jirauenergia.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#primaryimage"},"image":{"@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#primaryimage"},"thumbnailUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2020-10-23-at-08.20.20.jpeg","datePublished":"2021-09-13T22:07:32+00:00","dateModified":"2021-10-21T14:25:36+00:00","breadcrumb":{"@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#primaryimage","url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2020-10-23-at-08.20.20.jpeg","contentUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/WhatsApp-Image-2020-10-23-at-08.20.20.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-conservacao-da-flora#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.jirauenergia.com.br\/"},{"@type":"ListItem","position":2,"name":"Programa de Conserva\u00e7\u00e3o da Flora"}]},{"@type":"WebSite","@id":"https:\/\/www.jirauenergia.com.br\/#website","url":"https:\/\/www.jirauenergia.com.br\/","name":"JIRAU ENERGY","description":"","publisher":{"@id":"https:\/\/www.jirauenergia.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jirauenergia.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.jirauenergia.com.br\/#organization","name":"JIRAU ENERGY","url":"https:\/\/www.jirauenergia.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png","contentUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png","width":300,"height":86,"caption":"Jirau Energia"},"image":{"@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/programas\/9740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/programas"}],"about":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/types\/programas"}],"version-history":[{"count":1,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/programas\/9740\/revisions"}],"predecessor-version":[{"id":9741,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/programas\/9740\/revisions\/9741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/media\/13232"}],"wp:attachment":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/media?parent=9740"}],"wp:term":[{"taxonomy":"categoria_de_programas","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/categoria_de_programas?post=9740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}