{"id":9736,"date":"2021-09-13T18:06:06","date_gmt":"2021-09-13T22:06:06","guid":{"rendered":"https:\/\/www.jirauenergia.com.br\/?post_type=programas&#038;p=9736"},"modified":"2021-10-21T17:22:22","modified_gmt":"2021-10-21T20:22:22","slug":"programa-de-desmatamento-do-reservatorio","status":"publish","type":"programas","link":"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-desmatamento-do-reservatorio","title":{"rendered":"Programa de Desmatamento do Reservat\u00f3rio"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Objetivo<\/strong><br>Este Programa foi destinado \u00e0 estabelecer diretrizes e procedimentos estrat\u00e9gicos para a supress\u00e3o da cobertura vegetal de \u00e1reas situadas no interior do reservat\u00f3rio da UHE Jirau e de demais \u00e1reas necess\u00e1rias \u00e0s obras e estruturas da UHE Jirau, visando evitar e reduzir efeitos adversos da degrada\u00e7\u00e3o de mat\u00e9ria org\u00e2nica sem preju\u00edzos para a qualidade da \u00e1gua, fauna e flora.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Resumo<\/strong><br>O Programa foi destinado ao planejamento e execu\u00e7\u00e3o do desmatamento e limpeza de \u00e1reas necess\u00e1rias \u00e0s obras e aquelas a serem inundadas pelo reservat\u00f3rio do UHE Jirau, envolvendo o mapeamento, o desenvolvimento de estudos para a defini\u00e7\u00e3o das \u00e1reas a serem desmatadas, a elabora\u00e7\u00e3o de invent\u00e1rio florestal, a obten\u00e7\u00e3o de Autoriza\u00e7\u00e3o de Supress\u00e3o de Vegeta\u00e7\u00e3o (ASV) e a execu\u00e7\u00e3o da supress\u00e3o de vegeta\u00e7\u00e3o propriamente.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Fase Atual<\/strong><br>Em desenvolvimento<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Executor<\/strong><br>Intertechne Consultores S.A.(planejamento) e empresas executoras do desmatamento<\/li><\/ul>","protected":false},"featured_media":13254,"template":"","categoria_de_programas":[52],"class_list":["post-9736","programas","type-programas","status-publish","has-post-thumbnail","hentry","categoria_de_programas-programas-ambientais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Programa de Desmatamento do Reservat\u00f3rio - Jirau Energia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-desmatamento-do-reservatorio\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programa de Desmatamento do Reservat\u00f3rio - Jirau Energia\" \/>\n<meta property=\"og:description\" content=\"ObjetivoEste Programa foi destinado \u00e0 estabelecer diretrizes e procedimentos estrat\u00e9gicos para a supress\u00e3o da cobertura vegetal de \u00e1reas situadas no interior do reservat\u00f3rio da UHE Jirau e de demais \u00e1reas necess\u00e1rias \u00e0s obras e estruturas da UHE Jirau, visando evitar e reduzir efeitos adversos da degrada\u00e7\u00e3o de mat\u00e9ria org\u00e2nica sem preju\u00edzos para a qualidade da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-desmatamento-do-reservatorio\" \/>\n<meta property=\"og:site_name\" content=\"Jirau Energia\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-21T20:22:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/IMG-20170623-WA0021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"584\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio\",\"url\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio\",\"name\":\"Programa de Desmatamento do Reservat\u00f3rio - Jirau Energia\",\"isPartOf\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/IMG-20170623-WA0021.jpg\",\"datePublished\":\"2021-09-13T22:06:06+00:00\",\"dateModified\":\"2021-10-21T20:22:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#primaryimage\",\"url\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/IMG-20170623-WA0021.jpg\",\"contentUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/IMG-20170623-WA0021.jpg\",\"width\":1040,\"height\":584},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.jirauenergia.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programa de Desmatamento do Reservat\u00f3rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#website\",\"url\":\"https:\/\/www.jirauenergia.com.br\/\",\"name\":\"Jirau Energia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jirauenergia.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#organization\",\"name\":\"Jirau Energia\",\"url\":\"https:\/\/www.jirauenergia.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png\",\"contentUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png\",\"width\":300,\"height\":86,\"caption\":\"Jirau Energia\"},\"image\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programa de Desmatamento do Reservat\u00f3rio - Jirau Energia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-desmatamento-do-reservatorio","og_locale":"en_US","og_type":"article","og_title":"Programa de Desmatamento do Reservat\u00f3rio - Jirau Energia","og_description":"ObjetivoEste Programa foi destinado \u00e0 estabelecer diretrizes e procedimentos estrat\u00e9gicos para a supress\u00e3o da cobertura vegetal de \u00e1reas situadas no interior do reservat\u00f3rio da UHE Jirau e de demais \u00e1reas necess\u00e1rias \u00e0s obras e estruturas da UHE Jirau, visando evitar e reduzir efeitos adversos da degrada\u00e7\u00e3o de mat\u00e9ria org\u00e2nica sem preju\u00edzos para a qualidade da [&hellip;]","og_url":"https:\/\/www.jirauenergia.com.br\/en\/?programas=programa-de-desmatamento-do-reservatorio","og_site_name":"Jirau Energia","article_modified_time":"2021-10-21T20:22:22+00:00","og_image":[{"width":1040,"height":584,"url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/IMG-20170623-WA0021.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio","url":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio","name":"Programa de Desmatamento do Reservat\u00f3rio - Jirau Energia","isPartOf":{"@id":"https:\/\/www.jirauenergia.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#primaryimage"},"image":{"@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#primaryimage"},"thumbnailUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/IMG-20170623-WA0021.jpg","datePublished":"2021-09-13T22:06:06+00:00","dateModified":"2021-10-21T20:22:22+00:00","breadcrumb":{"@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#primaryimage","url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/IMG-20170623-WA0021.jpg","contentUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/09\/IMG-20170623-WA0021.jpg","width":1040,"height":584},{"@type":"BreadcrumbList","@id":"https:\/\/www.jirauenergia.com.br\/?programas=programa-de-desmatamento-do-reservatorio#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.jirauenergia.com.br\/"},{"@type":"ListItem","position":2,"name":"Programa de Desmatamento do Reservat\u00f3rio"}]},{"@type":"WebSite","@id":"https:\/\/www.jirauenergia.com.br\/#website","url":"https:\/\/www.jirauenergia.com.br\/","name":"JIRAU ENERGY","description":"","publisher":{"@id":"https:\/\/www.jirauenergia.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jirauenergia.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.jirauenergia.com.br\/#organization","name":"JIRAU ENERGY","url":"https:\/\/www.jirauenergia.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png","contentUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png","width":300,"height":86,"caption":"Jirau Energia"},"image":{"@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/programas\/9736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/programas"}],"about":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/types\/programas"}],"version-history":[{"count":1,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/programas\/9736\/revisions"}],"predecessor-version":[{"id":9737,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/programas\/9736\/revisions\/9737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/media\/13254"}],"wp:attachment":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/media?parent=9736"}],"wp:term":[{"taxonomy":"categoria_de_programas","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/categoria_de_programas?post=9736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}