{"id":12816,"date":"2019-11-28T12:15:00","date_gmt":"2019-11-28T15:15:00","guid":{"rendered":"https:\/\/www.jirauenergia.com.br\/?p=12816"},"modified":"2021-10-18T12:18:49","modified_gmt":"2021-10-18T15:18:49","slug":"usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia","status":"publish","type":"post","link":"https:\/\/www.jirauenergia.com.br\/en\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/","title":{"rendered":"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Estudantes de Engenharia El\u00e9trica da Universidade Federal de Rond\u00f4nia (UNIR) visitaram a Usina Hidrel\u00e9trica (UHE) Jirau acompanhados do professor Jos\u00e9 Ezequiel Ramos. O grupo foi recebido pela equipe de Rela\u00e7\u00f5es Institucionais da Empresa e conheceu a Casa de For\u00e7a, Vertedouro, Subesta\u00e7\u00e3o Isolada a G\u00e1s e Sala de Controle. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o professor Ezequiel Ramos, as visitas enriquecem o aprendizado. &#8220;A gente faz essas visitas institucionais com o intuito dos alunos conhecerem de perto a realidade do que est\u00e3o vendo em sala de aula, por exemplo: estudou sobre turbinas el\u00e9tricas, mas ver a turbina funcionando \u00e9 outra dimens\u00e3o, completa a aprendizagem&#8221;, afirma o professor.<br>Para a estudante Eloiza Costa Barros, foi uma \u00f3tima aula de campo. \u201cAs visitas agregam conhecimento. J\u00e1 \u00e9 a segunda vez que visito uma hidrel\u00e9trica e agora temos uma mat\u00e9ria espec\u00edfica sobre hidrel\u00e9trica, ent\u00e3o viemos com um conhecimento pr\u00e9vio muito maior e aqui nos deparamos com muita coisa que j\u00e1 hav\u00edamos aprendido, foi bem interessante&#8221;, conta Barros.<br>Em seguida, os acad\u00eamicos conheceram, no Centro Cultural de Nova Mutum Paran\u00e1, as pe\u00e7as arqueol\u00f3gicas que foram resgatadas durante a fase de implanta\u00e7\u00e3o da Usina. A exposi\u00e7\u00e3o do acervo \u00e9 aberta ao p\u00fablico, de segunda a quinta-feira, no hor\u00e1rio das 7h30 \u00e0s 17h e \u00e0s sextas-feiras, at\u00e9 \u00e0s 16h. Todas as visitas s\u00e3o acompanhadas e monitoradas pela equipe de arqueologia que atua no local. J\u00e1 a Usina Hidrel\u00e9trica Jirau recebe visitas institucionais agendadas com anteced\u00eancia pelo e-mail visita@esbr.com.br. Para mais informa\u00e7\u00f5es, o interessado tamb\u00e9m pode entrar em contato via telefone pelo n\u00famero 0800 647 77 47.<\/p>","protected":false},"excerpt":{"rendered":"<p>Estudantes de Engenharia El\u00e9trica da Universidade Federal de Rond\u00f4nia (UNIR) visitaram a Usina Hidrel\u00e9trica (UHE) Jirau acompanhados do professor Jos\u00e9 Ezequiel Ramos. O grupo foi recebido pela equipe de Rela\u00e7\u00f5es Institucionais da Empresa e conheceu a Casa de For\u00e7a, Vertedouro, Subesta\u00e7\u00e3o Isolada a G\u00e1s e Sala de Controle. De acordo com o professor Ezequiel Ramos, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":12817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[37],"tags":[],"tipo_de_noticias":[],"tipos_de_inovacao":[],"categoria_episodios":[],"categorias_de_vaga":[],"categoria_de_programas":[],"alfabeto_glossario":[],"categorias_de_pdf":[],"projetos_pdi":[],"class_list":["post-12816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia - Jirau Energia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jirauenergia.com.br\/en\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia - Jirau Energia\" \/>\n<meta property=\"og:description\" content=\"Estudantes de Engenharia El\u00e9trica da Universidade Federal de Rond\u00f4nia (UNIR) visitaram a Usina Hidrel\u00e9trica (UHE) Jirau acompanhados do professor Jos\u00e9 Ezequiel Ramos. O grupo foi recebido pela equipe de Rela\u00e7\u00f5es Institucionais da Empresa e conheceu a Casa de For\u00e7a, Vertedouro, Subesta\u00e7\u00e3o Isolada a G\u00e1s e Sala de Controle. De acordo com o professor Ezequiel Ramos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jirauenergia.com.br\/en\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Jirau Energia\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-28T15:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T15:18:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2189\" \/>\n\t<meta property=\"og:image:height\" content=\"1460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jirauenergia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jirauenergia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/\"},\"author\":{\"name\":\"jirauenergia\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/person\/8452dd861e3764906dd8aaa2cd653525\"},\"headline\":\"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia\",\"datePublished\":\"2019-11-28T15:15:00+00:00\",\"dateModified\":\"2021-10-18T15:18:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/\"},\"wordCount\":295,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/\",\"url\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/\",\"name\":\"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia - Jirau Energia\",\"isPartOf\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg\",\"datePublished\":\"2019-11-28T15:15:00+00:00\",\"dateModified\":\"2021-10-18T15:18:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#primaryimage\",\"url\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg\",\"contentUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg\",\"width\":2189,\"height\":1460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.jirauenergia.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#website\",\"url\":\"https:\/\/www.jirauenergia.com.br\/\",\"name\":\"Jirau Energia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jirauenergia.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#organization\",\"name\":\"Jirau Energia\",\"url\":\"https:\/\/www.jirauenergia.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png\",\"contentUrl\":\"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png\",\"width\":300,\"height\":86,\"caption\":\"Jirau Energia\"},\"image\":{\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/person\/8452dd861e3764906dd8aaa2cd653525\",\"name\":\"jirauenergia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.jirauenergia.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5aedeb352cd31eb2b3d0be18147849090117adb8c7f2b8420d2aed5457179913?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5aedeb352cd31eb2b3d0be18147849090117adb8c7f2b8420d2aed5457179913?s=96&d=mm&r=g\",\"caption\":\"jirauenergia\"},\"sameAs\":[\"http:\/\/34.95.145.5\"],\"url\":\"https:\/\/www.jirauenergia.com.br\/en\/author\/jirauenergia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia - Jirau Energia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jirauenergia.com.br\/en\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/","og_locale":"en_US","og_type":"article","og_title":"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia - Jirau Energia","og_description":"Estudantes de Engenharia El\u00e9trica da Universidade Federal de Rond\u00f4nia (UNIR) visitaram a Usina Hidrel\u00e9trica (UHE) Jirau acompanhados do professor Jos\u00e9 Ezequiel Ramos. O grupo foi recebido pela equipe de Rela\u00e7\u00f5es Institucionais da Empresa e conheceu a Casa de For\u00e7a, Vertedouro, Subesta\u00e7\u00e3o Isolada a G\u00e1s e Sala de Controle. De acordo com o professor Ezequiel Ramos, [&hellip;]","og_url":"https:\/\/www.jirauenergia.com.br\/en\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/","og_site_name":"Jirau Energia","article_published_time":"2019-11-28T15:15:00+00:00","article_modified_time":"2021-10-18T15:18:49+00:00","og_image":[{"width":2189,"height":1460,"url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg","type":"image\/jpeg"}],"author":"jirauenergia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jirauenergia","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#article","isPartOf":{"@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/"},"author":{"name":"jirauenergia","@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/person\/8452dd861e3764906dd8aaa2cd653525"},"headline":"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia","datePublished":"2019-11-28T15:15:00+00:00","dateModified":"2021-10-18T15:18:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/"},"wordCount":295,"commentCount":0,"publisher":{"@id":"https:\/\/www.jirauenergia.com.br\/#organization"},"image":{"@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/","url":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/","name":"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia - Jirau Energia","isPartOf":{"@id":"https:\/\/www.jirauenergia.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#primaryimage"},"image":{"@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg","datePublished":"2019-11-28T15:15:00+00:00","dateModified":"2021-10-18T15:18:49+00:00","breadcrumb":{"@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#primaryimage","url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg","contentUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/10\/Visitantes_na_Casa_de_Forca_da_Margem_Direita_da_UHE_Jirau.jpg","width":2189,"height":1460},{"@type":"BreadcrumbList","@id":"https:\/\/www.jirauenergia.com.br\/usina-hidreletrica-jirau-recebe-estudantes-da-universidade-federal-de-rondonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.jirauenergia.com.br\/"},{"@type":"ListItem","position":2,"name":"Usina Hidrel\u00e9trica Jirau recebe Estudantes da Universidade Federal de Rond\u00f4nia"}]},{"@type":"WebSite","@id":"https:\/\/www.jirauenergia.com.br\/#website","url":"https:\/\/www.jirauenergia.com.br\/","name":"JIRAU ENERGY","description":"","publisher":{"@id":"https:\/\/www.jirauenergia.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jirauenergia.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.jirauenergia.com.br\/#organization","name":"JIRAU ENERGY","url":"https:\/\/www.jirauenergia.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png","contentUrl":"https:\/\/www.jirauenergia.com.br\/wp-content\/uploads\/2021\/06\/cropped-logo-jirau-energia-1-1.png","width":300,"height":86,"caption":"Jirau Energia"},"image":{"@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/person\/8452dd861e3764906dd8aaa2cd653525","name":"jirauenergia","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.jirauenergia.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5aedeb352cd31eb2b3d0be18147849090117adb8c7f2b8420d2aed5457179913?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aedeb352cd31eb2b3d0be18147849090117adb8c7f2b8420d2aed5457179913?s=96&d=mm&r=g","caption":"jirauenergia"},"sameAs":["http:\/\/34.95.145.5"],"url":"https:\/\/www.jirauenergia.com.br\/en\/author\/jirauenergia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/posts\/12816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/comments?post=12816"}],"version-history":[{"count":1,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/posts\/12816\/revisions"}],"predecessor-version":[{"id":12818,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/posts\/12816\/revisions\/12818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/media\/12817"}],"wp:attachment":[{"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/media?parent=12816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/categories?post=12816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/tags?post=12816"},{"taxonomy":"tipo_de_noticias","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/tipo_de_noticias?post=12816"},{"taxonomy":"tipos_de_inovacao","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/tipos_de_inovacao?post=12816"},{"taxonomy":"categoria_episodios","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/categoria_episodios?post=12816"},{"taxonomy":"categorias_de_vaga","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/categorias_de_vaga?post=12816"},{"taxonomy":"categoria_de_programas","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/categoria_de_programas?post=12816"},{"taxonomy":"alfabeto_glossario","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/alfabeto_glossario?post=12816"},{"taxonomy":"categorias_de_pdf","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/categorias_de_pdf?post=12816"},{"taxonomy":"projetos_pdi","embeddable":true,"href":"https:\/\/www.jirauenergia.com.br\/en\/wp-json\/wp\/v2\/projetos_pdi?post=12816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}